{"id":9501,"date":"2026-08-05T09:29:31","date_gmt":"2026-08-05T16:29:31","guid":{"rendered":"https:\/\/www.first5coco.org\/our-impact\/"},"modified":"2026-08-06T11:26:40","modified_gmt":"2026-08-06T18:26:40","slug":"nuestro-impacto","status":"publish","type":"page","link":"https:\/\/www.first5coco.org\/es\/nuestro-impacto\/","title":{"rendered":"Nuestro Impacto"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>&#8230;<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/www.first5coco.org\/es\/nuestro-impacto\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":37,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/gallery-page.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-9501","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.first5coco.org\/es\/nuestro-impacto\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"First 5 Contra Costa | Making the First 5 Years Count\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Nuestro Impacto | First 5 Contra Costa\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.first5coco.org\/es\/nuestro-impacto\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-08-05T16:29:31+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-08-06T18:26:40+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Nuestro Impacto | First 5 Contra Costa\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/nuestro-impacto\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/nuestro-impacto\\\/#listItem\",\"name\":\"Nuestro Impacto\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/nuestro-impacto\\\/#listItem\",\"position\":2,\"name\":\"Nuestro Impacto\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/#organization\",\"name\":\"First 5 Contra Costa\",\"description\":\"Making the First 5 Years Count\",\"url\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/nuestro-impacto\\\/#webpage\",\"url\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/nuestro-impacto\\\/\",\"name\":\"Nuestro Impacto | First 5 Contra Costa\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/nuestro-impacto\\\/#breadcrumblist\"},\"datePublished\":\"2026-08-05T09:29:31-07:00\",\"dateModified\":\"2026-08-06T11:26:40-07:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/\",\"name\":\"First5 coco\",\"description\":\"Making the First 5 Years Count\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Nuestro Impacto | First 5 Contra Costa","description":"","canonical_url":"https:\/\/www.first5coco.org\/es\/nuestro-impacto\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.first5coco.org\/es\/nuestro-impacto\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.first5coco.org\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/www.first5coco.org\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.first5coco.org\/es\/nuestro-impacto\/#listItem","name":"Nuestro Impacto"}},{"@type":"ListItem","@id":"https:\/\/www.first5coco.org\/es\/nuestro-impacto\/#listItem","position":2,"name":"Nuestro Impacto","previousItem":{"@type":"ListItem","@id":"https:\/\/www.first5coco.org\/es\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/www.first5coco.org\/es\/#organization","name":"First 5 Contra Costa","description":"Making the First 5 Years Count","url":"https:\/\/www.first5coco.org\/es\/"},{"@type":"WebPage","@id":"https:\/\/www.first5coco.org\/es\/nuestro-impacto\/#webpage","url":"https:\/\/www.first5coco.org\/es\/nuestro-impacto\/","name":"Nuestro Impacto | First 5 Contra Costa","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.first5coco.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.first5coco.org\/es\/nuestro-impacto\/#breadcrumblist"},"datePublished":"2026-08-05T09:29:31-07:00","dateModified":"2026-08-06T11:26:40-07:00"},{"@type":"WebSite","@id":"https:\/\/www.first5coco.org\/es\/#website","url":"https:\/\/www.first5coco.org\/es\/","name":"First5 coco","description":"Making the First 5 Years Count","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.first5coco.org\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"First 5 Contra Costa | Making the First 5 Years Count","og:type":"article","og:title":"Nuestro Impacto | First 5 Contra Costa","og:url":"https:\/\/www.first5coco.org\/es\/nuestro-impacto\/","article:published_time":"2026-08-05T16:29:31+00:00","article:modified_time":"2026-08-06T18:26:40+00:00","twitter:card":"summary","twitter:title":"Nuestro Impacto | First 5 Contra Costa"},"aioseo_meta_data":{"post_id":"9501","title":null,"description":null,"keywords":null,"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-08-05 18:11:51","updated":"2026-08-19 21:51:43","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.first5coco.org\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tNuestro Impacto\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.first5coco.org\/es\/"},{"label":"Nuestro Impacto","link":"https:\/\/www.first5coco.org\/es\/nuestro-impacto\/"}],"_links":{"self":[{"href":"https:\/\/www.first5coco.org\/es\/wp-json\/wp\/v2\/pages\/9501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.first5coco.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.first5coco.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.first5coco.org\/es\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/www.first5coco.org\/es\/wp-json\/wp\/v2\/comments?post=9501"}],"version-history":[{"count":6,"href":"https:\/\/www.first5coco.org\/es\/wp-json\/wp\/v2\/pages\/9501\/revisions"}],"predecessor-version":[{"id":9545,"href":"https:\/\/www.first5coco.org\/es\/wp-json\/wp\/v2\/pages\/9501\/revisions\/9545"}],"wp:attachment":[{"href":"https:\/\/www.first5coco.org\/es\/wp-json\/wp\/v2\/media?parent=9501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}