{"id":7695,"date":"2025-08-07T09:27:47","date_gmt":"2025-08-07T16:27:47","guid":{"rendered":"https:\/\/www.first5coco.org\/?p=7695"},"modified":"2025-08-07T10:14:23","modified_gmt":"2025-08-07T17:14:23","slug":"boletin-de-agosto","status":"publish","type":"post","link":"https:\/\/www.first5coco.org\/es\/boletin-de-agosto\/","title":{"rendered":"Bolet\u00edn de agosto"},"content":{"rendered":"<h2><span style=\"color: #003366;\">Construyendo un futuro m\u00e1s inclusivo:<\/span><\/h2>\n<h4 style=\"text-align: left;\" align=\"center\"><span style=\"color: #003366;\">Celebrando los numerosos esfuerzos para mejorar los programas de cuidado infantil capacidad de incluir a ni\u00f1os con retrasos, discapacidades, o preocupaciones socioemocionales<\/span><\/h4>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7698\" src=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/08\/providers.jpg\" alt=\"\" width=\"700\" height=\"394\" srcset=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/08\/providers.jpg 950w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/08\/providers-250x141.jpg 250w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/08\/providers-768x433.jpg 768w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p align=\"left\">Durante los \u00faltimos dos a\u00f1os, los Primeros 5 de Contra Costa ha implementado medidas estrat\u00e9gicas centradas en la comunidad para\u00a0<a href=\"https:\/\/www.first5coco.org\/es\/educacion-de-la-primera-infancia\/apoyando-el-cuidado-de-ninos-y-la-educacion-temprana-e-inclusiva\/\" target=\"_blank\" rel=\"noopener noreferrer\">promover la inclusi\u00f3n de los ni\u00f1os peque\u00f1os y sus familias a trav\u00e9s de iniciativas financiadas por la Medida X<\/a>. Desde el lanzamiento de un nuevo programa de desarrollo de capacidades y consulta sobre salud mental hasta el fortalecimiento de las alianzas comunitarias, nuestro trabajo ha sido impactante y de amplio alcance.<\/p>\n<p align=\"left\">Impartimos y apoyamos capacitaciones para proveedores de primera infancia, pusimos a prueba programas innovadores como el \u00abpase de compras\u00bb para equiparlos con herramientas que les permitan crear entornos m\u00e1s inclusivos y\u00a0<a href=\"https:\/\/www.first5coco.org\/es\/educacion-de-la-primera-infancia\/promoviendo-entornos-de-aprendizaje-inclusivos\/\" target=\"_blank\" rel=\"noopener noreferrer\">producimos videos<\/a>\u00a0que muestran maneras pr\u00e1cticas de usar estas herramientas en situaciones cotidianas. Para impulsar estos esfuerzos, recientemente lanzamos un sitio web actualizado de\u00a0<a href=\"https:\/\/helpmegrowcoco.org\/?lang=es\" target=\"_blank\" rel=\"noopener noreferrer\">Help Me Grow Contra Costa, que ahora incluye videos en varios idiomas<\/a>\u00a0para reflejar y servir mejor a nuestra comunidad diversa. Este sitio web tiene como objetivo ayudar a las familias y a los proveedores de cuidado infantil a comprender la importancia de las evaluaciones del desarrollo para ni\u00f1os peque\u00f1os, d\u00f3nde acceder a ellas y c\u00f3mo acceder a los servicios cuando los necesiten. Para ampliar nuestro alcance, tambi\u00e9n nos asociamos con cinco organizaciones comunitarias para realizar actividades de comunicaci\u00f3n sobre las evaluaciones y llegar a a\u00fan m\u00e1s familias y proveedores.<\/p>\n<p align=\"left\">Haga clic a continuaci\u00f3n para ver algunos materiales de comunicaci\u00f3n creados a trav\u00e9s de estas asociaciones:<\/p>\n<ul>\n<li><a href=\"https:\/\/the-center.my.canva.site\/ccc-screening4providers\" target=\"_blank\" rel=\"noopener noreferrer\">Center for Early Childhood Connections (ingl\u00e9s y espa\u00f1ol<\/a>)<\/li>\n<li><a href=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/07\/CEP_POSTCARDS_English-Spanish.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Community Education Partnerships (ingl\u00e9s y espa\u00f1ol)<\/a><\/li>\n<li><a href=\"https:\/\/www.facebook.com\/eltimpanooakland\/videos\/1378874143365999\" target=\"_blank\" rel=\"noopener noreferrer\">El T\u00edmpano video (Mam, disponible con subt\u00edtulos en varios idiomas)<\/a><\/li>\n<li><a href=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/07\/PAAACT-Postcrads.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Parental African American Achievement Collaborative Team (ingles)<\/a><\/li>\n<li><a href=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/07\/We_Care_Parent_Network_POSTCARDS.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">We Care Parent Network (ingl\u00e9s y espa\u00f1ol)<\/a><\/li>\n<\/ul>\n<p align=\"left\">Tambi\u00e9n organizamos recientemente una reuni\u00f3n a nivel de condado sobre la neurodiversidad (m\u00e1s informaci\u00f3n a continuaci\u00f3n), completamos un proceso de participaci\u00f3n de las personas interesadas y publicamos un\u00a0<a href=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2024\/11\/First5_report_11.15.24_spanish.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">informe completo (espa\u00f1ol)<\/a>\u00a0con recomendaciones que guiaron el trabajo de este a\u00f1o y el trabajo futuro.<\/p>\n<p align=\"left\">Estas habilidades del desarrollo reflejan nuestro compromiso con la creaci\u00f3n de sistemas que verdaderamente apoyen a todos los ni\u00f1os y familias, y los logros del a\u00f1o pasado sientan una base s\u00f3lida para el futuro inclusivo que juntos forjamos.<\/p>\n<p align=\"left\">Un agradecimiento especial a la Junta de Supervisores por la financiaci\u00f3n para trabajar en esta importante prioridad, a los numerosos contratistas que nos ayudaron a prestar estos servicios, a los colaboradores que ayudaron a difundir estas iniciativas y a los proveedores de cuidado infantil y las familias que participaron en ellas.<\/p>\n<p align=\"left\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3744\" src=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px.png\" alt=\"\" width=\"1536\" height=\"89\" srcset=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px.png 1536w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px-250x14.png 250w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px-1024x59.png 1024w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px-768x45.png 768w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/><\/p>\n<h2><span style=\"color: #003366;\">Mantengamos el impulso:<\/span><\/h2>\n<h4><span style=\"color: #003366;\">Las grabaciones completas de nuestra Conferencia de Inclusi\u00f3n sobre la Neurodiversidad ya est\u00e1n disponibles<\/span><\/h4>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"Neurodiversity Convening (Event Recap)\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/yqFsrZHQxrE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p align=\"left\">Nos complace anunciar que\u00a0<a href=\"https:\/\/www.first5coco.org\/early-childhood-education\/supporting-inclusive-early-care-education-environments\/inclusion-convening-on-neurodiversity\/\" target=\"_blank\" rel=\"noopener noreferrer\">las grabaciones de video de cada sesi\u00f3n de nuestra Conferencia de Inclusi\u00f3n sobre la Neurodiversidad ya est\u00e1n disponibles para ver y compartir<\/a>.\u00a0En nuestro compromiso continuo con el fortalecimiento de la inclusi\u00f3n en la atenci\u00f3n y educaci\u00f3n temprana, estas grabaciones y recursos sirven como herramientas poderosas para revisar, reforzar y desarrollar las perspectivas y conexiones de nuestra reuni\u00f3n.<\/p>\n<p align=\"left\">En mayo, los Primeros 5 de Contra Costa organiz\u00f3 un evento para proveedores de cuidado infantil centrado en estrategias de inclusi\u00f3n para ni\u00f1os con neurodivergencia. El evento cont\u00f3 con la presentadora principal,\u00a0<a href=\"https:\/\/linktr.ee\/DaniMationENT\" target=\"_blank\" rel=\"noopener noreferrer\">Dani Bowman<\/a>, fundadora y directora ejecutiva de DaniMation Entertainment y miembro del elenco de la serie de Netflix\u00a0\u00abLove on the Spectrum\u00bb.<\/p>\n<p align=\"left\">El evento, con entradas agotadas, tambi\u00e9n incluy\u00f3 dos talleres con la Dra. Stephanie Tangsombatvisit, pediatra del desarrollo conductual, y Amanda Campbell, cofundadora y directora de servicios cl\u00ednicos del Centro para las Conexiones de la Primera Infancia, adem\u00e1s de una mesa redonda con familias para escuchar las experiencias y perspectivas de primera mano de padres que cr\u00edan ni\u00f1os con neurodivergencia en nuestra comunidad. Tambi\u00e9n se realiz\u00f3 una feria de recursos para que los asistentes conectaran con proveedores locales de intervenci\u00f3n temprana y organizaciones comunitarias.<\/p>\n<p align=\"left\"><a href=\"https:\/\/www.first5coco.org\/early-childhood-education\/supporting-inclusive-early-care-education-environments\/inclusion-convening-on-neurodiversity\/\" target=\"_blank\" rel=\"noopener noreferrer\">Hemos reunido todas las grabaciones, presentaciones y fotograf\u00edas en un solo lugar, ofreciendo la oportunidad de revisar momentos poderosos, explorar las sesiones y ampliar el impacto de nuestro aprendizaje colectivo.<\/a><\/p>\n<p align=\"left\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3744\" src=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px.png\" alt=\"\" width=\"1536\" height=\"89\" srcset=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px.png 1536w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px-250x14.png 250w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px-1024x59.png 1024w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px-768x45.png 768w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/><\/p>\n<h2 align=\"left\"><span style=\"color: #003366;\" data-olk-copy-source=\"MessageBody\">Las aplicaciones est\u00e1n abiertas para formar parte de nuestro Grupo de Padres Asesores<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p align=\"left\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6209\" src=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/01\/parent-advisory-group-2025.jpg\" alt=\"\" width=\"700\" height=\"437\" srcset=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/01\/parent-advisory-group-2025.jpg 1000w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/01\/parent-advisory-group-2025-250x156.jpg 250w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/01\/parent-advisory-group-2025-768x479.jpg 768w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>El\u00a0<a href=\"https:\/\/www.first5coco.org\/es\/como-trabajamos\/grupo-asesor-de-padres\/\" target=\"_blank\" rel=\"noopener noreferrer\">Grupo de Padres Asesores<\/a>\u00a0de los Primeros 5 de Contra Costa busca integrar las voces de los padres en el trabajo de los Primeros 5 de Contra Costa y apoyarlos como defensores de la primera infancia. El grupo se re\u00fane trimestralmente los s\u00e1bados por la ma\u00f1ana para compartir ideas sobre las necesidades familiares y mejorar el acceso a recursos. A lo largo del a\u00f1o, los miembros desarrollan habilidades de liderazgo, asesoran a los Primeros 5 de Contra Costa y conectan con otros padres y cuidadores.<\/p>\n<p>Ay\u00fadenos a garantizar que las voces de los padres est\u00e9n en el centro de los programas y servicios de la primera infancia.<\/p>\n<p><strong>\u00a1Corra la voz!<\/strong><\/p>\n<p><a href=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/07\/FY25.26-F5CC-Parent-Advisory-Group-Recruitment-Flyer.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Por favor comparta este volante<\/a>\u00a0con familias y grupos comunitarios interesados en unirse al Grupo de Padres Asesores. Juntos, podemos fortalecer la voz de los padres y generar un cambio positivo para los ni\u00f1os peque\u00f1os de Contra Costa.<\/p>\n<p><strong>\u00bfLe interesa unirse? \u00a1Inscr\u00edbase hoy mismo!<\/strong><\/p>\n<p><a href=\"https:\/\/forms.gle\/qdHHjsuHZSKTPaMXA\" target=\"_blank\" rel=\"noopener noreferrer\">Las solicitudes est\u00e1n abiertas hasta la medianoche del viernes 15 de agosto<\/a><a href=\"https:\/\/forms.gle\/qdHHjsuHZSKTPaMXA\" target=\"_blank\" rel=\"noopener noreferrer\">.<\/a>\u00a0Para solicitar, deber\u00e1 ser residente del Condado de Contra Costa con un hijo de entre 0 y 5 a\u00f1os y poder asistir a las reuniones presenciales los s\u00e1bados por la ma\u00f1ana. \u00a1Esperamos su respuesta!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3744\" src=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px.png\" alt=\"\" width=\"1536\" height=\"89\" srcset=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px.png 1536w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px-250x14.png 250w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px-1024x59.png 1024w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px-768x45.png 768w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/><\/p>\n<h2><span style=\"color: #003366;\" data-olk-copy-source=\"MessageBody\">Los Primeros 5 de Contra Costa llega a un vecindario cerca de usted<\/span><\/h2>\n<h4><span style=\"color: #003366;\" data-olk-copy-source=\"MessageBody\">\u00a1Visite, pase, salude y encuentre apoyo para usted y sus peque\u00f1os!<\/span><\/h4>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7696\" src=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/08\/library-event-1.png\" alt=\"\" width=\"701\" height=\"522\" srcset=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/08\/library-event-1.png 1200w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/08\/library-event-1-250x186.png 250w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/08\/library-event-1-1024x763.png 1024w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/08\/library-event-1-768x572.png 768w\" sizes=\"auto, (max-width: 701px) 100vw, 701px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Nos complace anunciar que los Primeros 5 de Contra Costa estar\u00e1 presente en varios eventos comunitarios por todo el condado este agosto, \u00a1y nos encantar\u00eda verlos all\u00ed!<\/p>\n<p>Si usted es padre, madre, cuidador o le apasiona apoyar a ni\u00f1os peque\u00f1os, esta es una excelente oportunidad para conectar con nuestro equipo. Compartiremos informaci\u00f3n \u00fatil sobre recursos y servicios locales dise\u00f1ados para apoyar a familias con ni\u00f1os de 0 a 5 a\u00f1os.<\/p>\n<p>Venga a saludarnos, recoja materiales, haga preguntas y descubra c\u00f3mo los Primeros 5 de Contra Costa puede ayudarles a usted y a su familia a prosperar. Vea a continuaci\u00f3n la lista de los pr\u00f3ximos eventos. \u00a1Esperamos verlos pronto!<\/p>\n<ul>\n<li>Martes 5 de agosto, 2025, 4pm, Richmond,\u00a0<a href=\"https:\/\/rysecenter.org\/events\/2025\/8\/5\/8th-annual-night-out-for-safety-amp-liberation\" target=\"_blank\" rel=\"noopener noreferrer\">RYSE for Night Out for Safety &amp; Liberation<\/a><\/li>\n<li>Martes 5 de agosto, 5pm, Concord,\u00a0<a href=\"https:\/\/ccclib.bibliocommons.com\/events\/6876ba22343180737b188132\" target=\"_blank\" rel=\"noopener noreferrer\">National Night Out<\/a><\/li>\n<li class=\"indent--1\">Martes 5 de agosto, 4pm, Pittsburg,\u00a0<a href=\"https:\/\/www.instagram.com\/p\/DMMEo73y9oY\/\" target=\"_blank\" rel=\"noopener noreferrer\">National Night Out<\/a><\/li>\n<li>Jueves 7 de agosto, 12pm, Pittsburg,\u00a0<a href=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/07\/1-330-Pittsburg-WBW-2025-Invitation-English.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">WIC World Breastfeeding Week Event<\/a><\/li>\n<li>Jueves 14 de agosto, 5pm, Richmond,\u00a0<a href=\"https:\/\/myemail.constantcontact.com\/Health---Wellness-at-Nicholl-Park-this-Thursday-night.html?soid=1111030452123&amp;aid=O_P-sxDyBRE\" target=\"_blank\" rel=\"noopener noreferrer\">PASOS &amp; Thrive Thursday<\/a><\/li>\n<li>Viernes 15 de agosto, Pittsburg, 4pm, Pittsburg Unified School District: Community Block Party at Martin Luther King Jr. Junior High School<\/li>\n<li>S\u00e1bado 16 de agosto, 8am, Pittsburg, Distrito Escolar Unificado de Pittsburg:\u00a0<a href=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/07\/pusd-literacy-fair.jpg\" target=\"_blank\" rel=\"noopener noreferrer\">Pittsburg Unified School District: Pancakes &amp; Pages Literacy Fair<\/a><\/li>\n<li>S\u00e1bado 16 de agosto, 10am, Bay Point,\u00a0<a href=\"https:\/\/www.ambroserec.org\/bay-point-community-resource-fair\" target=\"_blank\" rel=\"noopener noreferrer\">Bay Point Community Resource Fair<\/a><\/li>\n<li>S\u00e1bado 16 de agosto, 5pm,\u00a0<a href=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/07\/4th-Annual-BBQ-Flyer.jpg\" target=\"_blank\" rel=\"noopener noreferrer\">PAACT Back to School BBQ<\/a><\/li>\n<li>Viernes 22 de agosto, 10am, Concord,\u00a0<a href=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/07\/Flyer-for-WBW-2025-All-Languages.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">WIC World Breastfeeding Week Event<\/a><\/li>\n<li>Domingo 24 de agosto, 10am, El Sobrante,\u00a0<a href=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/07\/Community-Baby-Shower-Flyer.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">African American Community Baby Shower<\/a><\/li>\n<li>Jueves 28 de agosto, 4pm, Antioch,\u00a0<a href=\"https:\/\/www.contracosta.ca.gov\/CivicAlerts.aspx?AID=4743\" target=\"_blank\" rel=\"noopener noreferrer\">Contra Costa County Block Party<\/a><\/li>\n<\/ul>\n<p>\u00bfQuieres saber m\u00e1s?\u00a0El Centro de los Primeros 5 local es un lugar acogedor donde padres y cuidadores pueden encontrar apoyo, asistir a clases gratuitas y conectar con otras familias con ni\u00f1os peque\u00f1os.\u00a0<a href=\"https:\/\/www.first5coco.org\/es\/fortaleciendo-a-las-familias\/centros-de-los-primeros-5\/\" target=\"_blank\" rel=\"noopener noreferrer\">Haga clic aqu\u00ed para encontrar el Centro de los Primeros 5 m\u00e1s cercano y descubrir todo lo que ofrecen.<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3744\" src=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px.png\" alt=\"\" width=\"1536\" height=\"89\" srcset=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px.png 1536w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px-250x14.png 250w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px-1024x59.png 1024w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px-768x45.png 768w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/><\/p>\n<h2><span style=\"color: #003366;\" data-olk-copy-source=\"MessageBody\">Los Primeros 5 de Contra Costa le da la bienvenida a Stephanie Shieh como la nueva Oficial del Programa de Primera Infancia<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.first5coco.org\/first-5-contra-costa-welcomes-stephanie-shieh\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7565\" src=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/07\/StephS-400-1.jpg\" alt=\"\" width=\"250\" height=\"250\" srcset=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/07\/StephS-400-1.jpg 400w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/07\/StephS-400-1-250x250.jpg 250w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/07\/StephS-400-1-150x150.jpg 150w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Los Primeros 5 de Contra Costa se complace en\u00a0<a href=\"https:\/\/www.first5coco.org\/es\/primeros-5-contra-costa-da-la-bienvenida-a-stephanie-shieh\/\" target=\"_blank\" rel=\"noopener noreferrer\">anunciar y dar la bienvenida a Stephanie Shieh<\/a>\u00a0como nueva Oficial del Programa de Primera Infancia. Stephanie Shieh se une a los Primeros 5 de Contra Costa con una s\u00f3lida trayectoria en los sectores de educaci\u00f3n temprana y organizaciones sin fines de lucro, adem\u00e1s de un profundo compromiso con el desarrollo de sistemas educativos y de apoyo social para que sean m\u00e1s equitativos, accesibles e inclusivos.<\/p>\n<p>La experiencia previa de Stephanie incluye ser maestra de k\u00ednder y pre-k\u00ednder, donde desempe\u00f1\u00f3 un papel fundamental en la educaci\u00f3n de la primera infancia. Recientemente, dirigi\u00f3 programas de aprendizaje temprano y desarrollo profesional para familias con ni\u00f1os peque\u00f1os y educadores de cuidado infantil en la agencia de recursos y referencias del condado de Napa. Tambi\u00e9n posee una licenciatura en Biolog\u00eda y Educaci\u00f3n y una maestr\u00eda en Asuntos P\u00fablicos de la Escuela Goldman de Pol\u00edticas P\u00fablicas de la Universidad de California-Berkeley.<\/p>\n<p>Les invitamos a unirse a nosotros para dar la bienvenida a Stephanie Shieh, quien asumi\u00f3 su nuevo cargo el 15 de julio.<\/p>\n<p>Su amplio conocimiento de la educaci\u00f3n infantil temprana, junto con su experiencia en liderazgo de programas y pol\u00edticas, la capacita para generar un impacto significativo en los Primeros 5 de Contra Costa y nos ayudar\u00e1 a impulsar nuestra misi\u00f3n de garantizar que los ni\u00f1os peque\u00f1os de nuestro condado est\u00e9n sanos, listos para aprender y apoyados en familias y comunidades seguras y enriquecedoras.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3744\" src=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px.png\" alt=\"\" width=\"1536\" height=\"89\" srcset=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px.png 1536w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px-250x14.png 250w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px-1024x59.png 1024w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px-768x45.png 768w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/><\/p>\n<h2><span style=\"color: #003366;\" data-olk-copy-source=\"MessageBody\">Recursos de inmigraci\u00f3n para parejas y familias<\/span><\/h2>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.first5coco.org\/strengthening-families\/resources-for-partners-families\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-6732\" src=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/03\/first5-resources-partners-500.png\" alt=\"\" width=\"400\" height=\"264\" srcset=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/03\/first5-resources-partners-500.png 500w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/03\/first5-resources-partners-500-250x165.png 250w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p>En nuestro esfuerzo continuo por apoyar a las familias inmigrantes que enfrentan incertidumbre, ofrecimos en colaboraci\u00f3n con On the Move Bay Area una serie de capacitaciones para l\u00edderes de organizaciones y proveedores de cuidado infantil con licencia. Estas sesiones se centraron en ayudar a organizaciones comunitarias a guiar a las familias a trav\u00e9s de la planificaci\u00f3n legal y de emergencia con confianza y cuidado.<\/p>\n<p>Recientemente, tambi\u00e9n nos unimos a Stand Together Contra Costa en un Foro de Inmigraci\u00f3n organizado en el Contra Costa College. Los asistentes recibieron consultas legales privadas y gratuitas con abogados de inmigraci\u00f3n, participaron en talleres de empoderamiento \u00abConozca sus derechos\u00bb y de preparaci\u00f3n familiar, y accedieron a una vibrante feria de recursos comunitarios.<\/p>\n<p><a href=\"https:\/\/www.first5coco.org\/es\/fortaleciendo-a-las-familias\/recursos-de-inmigracion-socios-familias\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00a1Visite nuestra p\u00e1gina de Recursos de inmigraci\u00f3n para parejas y familias!<\/a><\/p>\n<p>Como su socio comunitario de confianza, hemos recopilado herramientas e informaci\u00f3n \u00fatiles para apoyar tanto a las familias inmigrantes como a los proveedores de servicios en tiempos dif\u00edciles, incluyendo nuestro\u00a0<a href=\"https:\/\/bit.ly\/supporting-families-toolkit\" target=\"_blank\" rel=\"noopener noreferrer\">Kit de herramientas de apoyo a familias inmigrantes<\/a>, que incluye secciones clave como Fortalecimiento Familiar, Preparaci\u00f3n Familiar, Conozca sus Derechos y Servicios Legales.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3744\" src=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px.png\" alt=\"\" width=\"1536\" height=\"89\" srcset=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px.png 1536w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px-250x14.png 250w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px-1024x59.png 1024w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2023\/08\/stroke-1px-768x45.png 768w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/><\/p>\n<h2><span style=\"color: #003366;\">\u00bfBuscas un espacio para tu pr\u00f3ximo evento o formaci\u00f3n?<\/span><\/h2>\n<h4><span style=\"color: #003366;\">Reserve los Centros de Conferencias de Primeros 5 Contra Costa<\/span><\/h4>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.first5coco.org\/reserve-the-first-5-contra-costa-conference-center\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7440\" src=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/07\/Conference-Room-gallery-2025.png\" alt=\"\" width=\"701\" height=\"340\" srcset=\"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/07\/Conference-Room-gallery-2025.png 2000w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/07\/Conference-Room-gallery-2025-250x121.png 250w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/07\/Conference-Room-gallery-2025-1024x497.png 1024w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/07\/Conference-Room-gallery-2025-768x372.png 768w, https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/07\/Conference-Room-gallery-2025-1536x745.png 1536w\" sizes=\"auto, (max-width: 701px) 100vw, 701px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Primeros 5 Contra Costa se complace en ofrecer un espacio profesional y acogedor para organizaciones dedicadas a apoyar a ni\u00f1os y familias en nuestra comunidad.\u00a0<a href=\"https:\/\/www.first5coco.org\/reserve-the-first-5-contra-costa-conference-center\/\" target=\"_blank\" rel=\"noopener noreferrer\">Nuestro Centro de Conferencias es el lugar ideal para reuniones, capacitaciones, talleres y actividades grupales.<\/a><\/p>\n<p>Caracter\u00edsticas del Centro de Conferencias:<\/p>\n<ul>\n<li>Amplia sala principal con capacidad para 57 asistentes.<\/li>\n<li>Dos peque\u00f1as salas de reuniones, ideales para debates en grupos peque\u00f1os y actividades interactivas.<\/li>\n<li>Equipado con tecnolog\u00eda, monitor de 100&#8243; para presentaciones y pizarra blanca.<\/li>\n<li>Confortable configuraci\u00f3n, con opciones flexibles para reuniones y espacio para caf\u00e9 y agua.<\/li>\n<li>Totalmente accesible para sillas de ruedas, incluyendo todas las entradas, ba\u00f1os y \u00e1reas comunes.<\/li>\n<li>Ubicaci\u00f3n conveniente, junto a la autopista 4 en Concord y muy cerca del BART.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.first5coco.org\/reserve-the-first-5-contra-costa-conference-center\/\">Haga clic aqu\u00ed para obtener m\u00e1s informaci\u00f3n<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Construyendo un futuro m\u00e1s inclusivo: Celebrando los numerosos esfuerzos para mejorar los programas de cuidado infantil capacidad de incluir a ni\u00f1os con retrasos, discapacidades, o preocupaciones socioemocionales &nbsp; &nbsp; Durante los \u00faltimos dos a\u00f1os, los Primeros 5 de Contra Costa ha implementado medidas estrat\u00e9gicas centradas en la comunidad para\u00a0promover la inclusi\u00f3n de los ni\u00f1os peque\u00f1os y sus familias a trav\u00e9s de iniciativas financiadas por la Medida X. Desde el lanzamiento de un nuevo programa de desarrollo de capacidades y consulta sobre salud mental hasta el fortalecimiento de las alianzas comunitarias, nuestro trabajo ha sido impactante y de amplio alcance. Impartimos&#8230;<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/www.first5coco.org\/es\/boletin-de-agosto\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":37,"featured_media":7716,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-7695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Brian Kelley\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.first5coco.org\/es\/boletin-de-agosto\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"First 5 Contra Costa | Making the First 5 Years Count\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Bolet\u00edn de agosto | First 5 Contra Costa\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.first5coco.org\/es\/boletin-de-agosto\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-08-07T16:27:47+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-08-07T17:14:23+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Bolet\u00edn de agosto | First 5 Contra Costa\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/boletin-de-agosto\\\/#article\",\"name\":\"Bolet\\u00edn de agosto | First 5 Contra Costa\",\"headline\":\"Bolet\\u00edn de agosto\",\"author\":{\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/author\\\/bkelley\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.first5coco.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/NEWSLETTER-agosoto.png\",\"width\":1536,\"height\":764,\"caption\":\"El texto en blanco sobre fondo verde azulado dice: \\u00abBolet\\u00edn Informativo de agosto de 2025\\u00bb.\"},\"datePublished\":\"2025-08-07T09:27:47-07:00\",\"dateModified\":\"2025-08-07T10:14:23-07:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/boletin-de-agosto\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/boletin-de-agosto\\\/#webpage\"},\"articleSection\":\"Sin categorizar, Opcional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/boletin-de-agosto\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/category\\\/sin-categorizar\\\/#listItem\",\"name\":\"Sin categorizar\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/category\\\/sin-categorizar\\\/#listItem\",\"position\":2,\"name\":\"Sin categorizar\",\"item\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/category\\\/sin-categorizar\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/boletin-de-agosto\\\/#listItem\",\"name\":\"Bolet\\u00edn de agosto\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/boletin-de-agosto\\\/#listItem\",\"position\":3,\"name\":\"Bolet\\u00edn de agosto\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/category\\\/sin-categorizar\\\/#listItem\",\"name\":\"Sin categorizar\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/#organization\",\"name\":\"First 5 Contra Costa\",\"description\":\"Making the First 5 Years Count\",\"url\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/author\\\/bkelley\\\/#author\",\"url\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/author\\\/bkelley\\\/\",\"name\":\"Brian Kelley\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/boletin-de-agosto\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f8dd6547e8a30fdbf549dca7e37177a20660b01a24fca97b8596ee8b8d3734b9?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Brian Kelley\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/boletin-de-agosto\\\/#webpage\",\"url\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/boletin-de-agosto\\\/\",\"name\":\"Bolet\\u00edn de agosto | First 5 Contra Costa\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/boletin-de-agosto\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/author\\\/bkelley\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/author\\\/bkelley\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.first5coco.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/NEWSLETTER-agosoto.png\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/boletin-de-agosto\\\/#mainImage\",\"width\":1536,\"height\":764,\"caption\":\"El texto en blanco sobre fondo verde azulado dice: \\u00abBolet\\u00edn Informativo de agosto de 2025\\u00bb.\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/boletin-de-agosto\\\/#mainImage\"},\"datePublished\":\"2025-08-07T09:27:47-07:00\",\"dateModified\":\"2025-08-07T10:14:23-07:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/\",\"name\":\"First5 coco\",\"description\":\"Making the First 5 Years Count\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.first5coco.org\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Bolet\u00edn de agosto | First 5 Contra Costa","description":"","canonical_url":"https:\/\/www.first5coco.org\/es\/boletin-de-agosto\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.first5coco.org\/es\/boletin-de-agosto\/#article","name":"Bolet\u00edn de agosto | First 5 Contra Costa","headline":"Bolet\u00edn de agosto","author":{"@id":"https:\/\/www.first5coco.org\/es\/author\/bkelley\/#author"},"publisher":{"@id":"https:\/\/www.first5coco.org\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/08\/NEWSLETTER-agosoto.png","width":1536,"height":764,"caption":"El texto en blanco sobre fondo verde azulado dice: \u00abBolet\u00edn Informativo de agosto de 2025\u00bb."},"datePublished":"2025-08-07T09:27:47-07:00","dateModified":"2025-08-07T10:14:23-07:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.first5coco.org\/es\/boletin-de-agosto\/#webpage"},"isPartOf":{"@id":"https:\/\/www.first5coco.org\/es\/boletin-de-agosto\/#webpage"},"articleSection":"Sin categorizar, Opcional"},{"@type":"BreadcrumbList","@id":"https:\/\/www.first5coco.org\/es\/boletin-de-agosto\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.first5coco.org\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/www.first5coco.org\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.first5coco.org\/es\/category\/sin-categorizar\/#listItem","name":"Sin categorizar"}},{"@type":"ListItem","@id":"https:\/\/www.first5coco.org\/es\/category\/sin-categorizar\/#listItem","position":2,"name":"Sin categorizar","item":"https:\/\/www.first5coco.org\/es\/category\/sin-categorizar\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.first5coco.org\/es\/boletin-de-agosto\/#listItem","name":"Bolet\u00edn de agosto"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.first5coco.org\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.first5coco.org\/es\/boletin-de-agosto\/#listItem","position":3,"name":"Bolet\u00edn de agosto","previousItem":{"@type":"ListItem","@id":"https:\/\/www.first5coco.org\/es\/category\/sin-categorizar\/#listItem","name":"Sin categorizar"}}]},{"@type":"Organization","@id":"https:\/\/www.first5coco.org\/es\/#organization","name":"First 5 Contra Costa","description":"Making the First 5 Years Count","url":"https:\/\/www.first5coco.org\/es\/"},{"@type":"Person","@id":"https:\/\/www.first5coco.org\/es\/author\/bkelley\/#author","url":"https:\/\/www.first5coco.org\/es\/author\/bkelley\/","name":"Brian Kelley","image":{"@type":"ImageObject","@id":"https:\/\/www.first5coco.org\/es\/boletin-de-agosto\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/f8dd6547e8a30fdbf549dca7e37177a20660b01a24fca97b8596ee8b8d3734b9?s=96&d=mm&r=g","width":96,"height":96,"caption":"Brian Kelley"}},{"@type":"WebPage","@id":"https:\/\/www.first5coco.org\/es\/boletin-de-agosto\/#webpage","url":"https:\/\/www.first5coco.org\/es\/boletin-de-agosto\/","name":"Bolet\u00edn de agosto | First 5 Contra Costa","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.first5coco.org\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.first5coco.org\/es\/boletin-de-agosto\/#breadcrumblist"},"author":{"@id":"https:\/\/www.first5coco.org\/es\/author\/bkelley\/#author"},"creator":{"@id":"https:\/\/www.first5coco.org\/es\/author\/bkelley\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.first5coco.org\/wp-content\/uploads\/2025\/08\/NEWSLETTER-agosoto.png","@id":"https:\/\/www.first5coco.org\/es\/boletin-de-agosto\/#mainImage","width":1536,"height":764,"caption":"El texto en blanco sobre fondo verde azulado dice: \u00abBolet\u00edn Informativo de agosto de 2025\u00bb."},"primaryImageOfPage":{"@id":"https:\/\/www.first5coco.org\/es\/boletin-de-agosto\/#mainImage"},"datePublished":"2025-08-07T09:27:47-07:00","dateModified":"2025-08-07T10:14:23-07:00"},{"@type":"WebSite","@id":"https:\/\/www.first5coco.org\/es\/#website","url":"https:\/\/www.first5coco.org\/es\/","name":"First5 coco","description":"Making the First 5 Years Count","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.first5coco.org\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"First 5 Contra Costa | Making the First 5 Years Count","og:type":"article","og:title":"Bolet\u00edn de agosto | First 5 Contra Costa","og:url":"https:\/\/www.first5coco.org\/es\/boletin-de-agosto\/","article:published_time":"2025-08-07T16:27:47+00:00","article:modified_time":"2025-08-07T17:14:23+00:00","twitter:card":"summary","twitter:title":"Bolet\u00edn de agosto | First 5 Contra Costa"},"aioseo_meta_data":{"post_id":"7695","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-08-07 15:56:04","updated":"2025-08-07 17:15:07","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.first5coco.org\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.first5coco.org\/es\/category\/sin-categorizar\/\" title=\"Sin categorizar\">Sin categorizar<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tBolet\u00edn de agosto\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.first5coco.org\/es\/"},{"label":"Sin categorizar","link":"https:\/\/www.first5coco.org\/es\/category\/sin-categorizar\/"},{"label":"Bolet\u00edn de agosto","link":"https:\/\/www.first5coco.org\/es\/boletin-de-agosto\/"}],"_links":{"self":[{"href":"https:\/\/www.first5coco.org\/es\/wp-json\/wp\/v2\/posts\/7695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.first5coco.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.first5coco.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.first5coco.org\/es\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/www.first5coco.org\/es\/wp-json\/wp\/v2\/comments?post=7695"}],"version-history":[{"count":7,"href":"https:\/\/www.first5coco.org\/es\/wp-json\/wp\/v2\/posts\/7695\/revisions"}],"predecessor-version":[{"id":7718,"href":"https:\/\/www.first5coco.org\/es\/wp-json\/wp\/v2\/posts\/7695\/revisions\/7718"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.first5coco.org\/es\/wp-json\/wp\/v2\/media\/7716"}],"wp:attachment":[{"href":"https:\/\/www.first5coco.org\/es\/wp-json\/wp\/v2\/media?parent=7695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.first5coco.org\/es\/wp-json\/wp\/v2\/categories?post=7695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.first5coco.org\/es\/wp-json\/wp\/v2\/tags?post=7695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}